{"id":11948,"date":"2026-05-13T06:00:41","date_gmt":"2026-05-13T04:00:41","guid":{"rendered":"https:\/\/www.mouclier.com\/?p=11948"},"modified":"2026-05-12T21:46:14","modified_gmt":"2026-05-12T19:46:14","slug":"alibaba-et-les-quarante-bandeurs-du-pont-neuf","status":"publish","type":"post","link":"https:\/\/www.mouclier.com\/index.php\/2026\/05\/13\/alibaba-et-les-quarante-bandeurs-du-pont-neuf\/","title":{"rendered":"ALIBABA ET LES QUARANTE BANDEURS DU PONT NEUF"},"content":{"rendered":"<p style=\"text-align: justify;\">Paname \u00e9touffe d\u00e9j\u00e0 sous les barri\u00e8res, les travaux, les files de v\u00e9los et les voitures fig\u00e9es comme des figurants oubli\u00e9s dans un mauvais r\u00eave, et voici qu\u2019arrive maintenant La Caverne du Pont Neuf. Apr\u00e8s Christo, il y a quarante ans, JR choisit cette fois de le transformer en carri\u00e8re de pierres g\u00e9antes, pour un d\u00e9cor de parc d\u2019attractions min\u00e9ral pos\u00e9 au milieu d\u2019une capitale d\u00e9j\u00e0 congestionn\u00e9e.<\/p>\n<p style=\"text-align: justify;\">On nous parle d&rsquo;un \u00ab dialogue entre pass\u00e9 et pr\u00e9sent \u00bb, mais le seul dialogue que les Parisiens entendent encore, c\u2019est celui des klaxons qui r\u00e9verb\u00e8rent entre la Samaritaine et \u00ab\u00a0l\u2019autel\u00a0\u00bb du cheval blanc du seigneur des Arnault. Une caverne pour une all\u00e9gorie, sorte de r\u00e9flexion que Platon dans \u00ab\u00a0La R\u00e9publique\u00a0\u00bb met en sc\u00e8ne : des humains encha\u00een\u00e9s et immobilis\u00e9s dans une caverne qui tournent le dos \u00e0 l&rsquo;entr\u00e9e et voient non pas les objets, mais les ombres, \u00e0 l&rsquo;or\u00e9e du BHV, la grotte de Dubuffet Campagnard Gratuits, cela a du sens. Les bimbos ne comprendront pas ce clin d&rsquo;oeil, mais cela n&rsquo;est pas grave.<\/p>\n<p style=\"text-align: justify;\">Certes, les promoteurs du projet jurent comme des manifestants aphones qu\u2019aucun financement public n\u2019est engag\u00e9. Mais \u00e0 Paris, m\u00eame les \u0153uvres pr\u00e9tendument gratuites, finissent toujours par co\u00fbter quelque chose aux contribuables : circulation paralys\u00e9e, s\u00e9curit\u00e9 mobilis\u00e9e, nettoyage, logistique, occupation de l\u2019espace public. Pendant qu\u2019on transforme le Pont Neuf en une grotte conceptuelle pour promeneurs en qu\u00eate de selfie min\u00e9ral, les rues voisines deviennent un labyrinthe d\u2019embouteillages et de d\u00e9tours, et pour rentrer \u00e0 la maison, c&rsquo;est plus difficile.<\/p>\n<p style=\"text-align: justify;\">Etrange fascination contemporaine pour des installations g\u00e9antes, vou\u00e9es \u00e0 la disparition apr\u00e8s quelques semaines, comme des feux d\u2019artifice culturels nourris de la \u00ab\u00a0conne\u00a0\u00bb et du sponsoring. Aujourd\u2019hui, une pr\u00e9tendue \u00ab caverne po\u00e9tique \u00bb\u2026 mais que les SDF puissent y trouver refuge ? Certainement pas. Circulez, il n\u2019y a rien \u00e0 voir.<\/p>\n<p style=\"text-align: justify;\">Demain, certainement un canyon de carton-p\u00e2te ou une montagne de b\u00e2ches non recycl\u00e9es pour notre r\u00e9chauffement \u00e0 tous. Paris m\u00e9rite mieux que ces attractions temporaires d\u00e9guis\u00e9es en r\u00e9flexion philosophique. Car une fois les photographes partis, les influenceurs envol\u00e9s et les discours artistiques balay\u00e9s par le premier courant d\u2019air m\u00e9diatique, il ne restera qu\u2019un souvenir co\u00fbteux, quelques kilom\u00e8tres de circulation perdue\u2026 et peut-\u00eatre, cette immense grotte urbaine devenue, selon la formule, la plus parisienne qui soit, une simple niche \u00e0 chiens pour capitale fatigu\u00e9e.<\/p>\n<p style=\"text-align: justify;\">FM<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify;\">Paname \u00e9touffe d\u00e9j\u00e0 sous les barri\u00e8res, les travaux, les files de v\u00e9los et les voitures fig\u00e9es comme des figurants oubli\u00e9s dans un mauvais r\u00eave, et voici qu\u2019arrive maintenant La Caverne du Pont Neuf. Apr\u00e8s Christo, il y a quarante ans, JR choisit cette fois de le transformer en carri\u00e8re de pierres g\u00e9antes, pour un d\u00e9cor de parc d\u2019attractions min\u00e9ral pos\u00e9 au milieu d\u2019une capitale d\u00e9j\u00e0 congestionn\u00e9e. <a href=\"https:\/\/www.mouclier.com\/index.php\/2024\/alibaba-et-les-quarante-bandeurs-du-pont-neuf\/\"><strong><em>Pour lire plus cliquer ici<\/em><\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"author":1,"featured_media":11954,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/posts\/11948"}],"collection":[{"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/comments?post=11948"}],"version-history":[{"count":10,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/posts\/11948\/revisions"}],"predecessor-version":[{"id":11959,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/posts\/11948\/revisions\/11959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/media\/11954"}],"wp:attachment":[{"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/media?parent=11948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/categories?post=11948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mouclier.com\/index.php\/wp-json\/wp\/v2\/tags?post=11948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}